{"id":2961,"date":"2018-11-13T13:54:54","date_gmt":"2018-11-13T11:54:54","guid":{"rendered":"https:\/\/olympiafestival.gr\/international-meeting-audiovisual-education-theoretical-and-practical-approaches\/"},"modified":"2021-12-09T15:07:50","modified_gmt":"2021-12-09T13:07:50","slug":"international-meeting-audiovisual-education-theoretical","status":"publish","type":"post","link":"https:\/\/olympiafestival.gr\/en\/news\/international-meeting-audiovisual-education-theoretical\/","title":{"rendered":"International Meeting Audiovisual Education: Theoretical and practical approaches"},"content":{"rendered":"<p style=\"text-align: justify;\">The Olympia International Film Festival, during its first edition in 1997, approached the issue of cinema in education and film education, by organizing an international conference in Ancient Olympia. Today, twenty years later, we are, once more, seeking the sign, by detecting the practices and concerns that have been developed over the past twenty years, and the achieved progress; the changes that were brought about by the enormous technological developments.<\/p>\n<p style=\"text-align: justify;\">Cinema is Reason. It is Language and Art. It is the main laboratory for research and innovation in the audiovisual field. Without cinema, audiovisual education does not exist.<\/p>\n<p style=\"text-align: justify;\">Through the suggestions of the conference, a wide range of audiovisual education issues is covered; theoretical and methodological approaches; reports on achievements and difficulties of tested applications; applications of small and larger structures, in small and larger scales, in formal and non-formal teaching methods. Arguments and counter-arguments will be developed about including audiovisual education in the curriculum as a compulsory lesson or as a lesson of choice. There will be references to the importance of joint actions at Pan-European and international level, and to ways of exchanging educational material and developing alternative networks.<\/p>\n<p style=\"text-align: justify;\">Ancient Olympia, Conference Hall<\/p>\n<p style=\"text-align: justify;\">7\/12\/2017, 09:30-14:00<\/p>\n<p style=\"text-align: justify;\">09:00-09:30 RECEPTION<\/p>\n<p style=\"text-align: justify;\">09:30 Dimitris Spyrou, artistic director of Olympia Film Festival, \u201cWelcome speech: Direction of the Meeting\u201d<\/p>\n<p style=\"text-align: justify;\">09:40 KEYNOTE SPEAKER<\/p>\n<p style=\"text-align: justify;\">Felix\u00a0Vanginderhuysen, General secretary of the European Children\u2019s Film Association (ECFA), senior advisor JEFF, Belgium, \u201cChildren&#8217;s Film and Film Education: the final destination\u201d<\/p>\n<p style=\"text-align: justify;\">10:00-11:30 FIRST SECTION<\/p>\n<p style=\"text-align: justify;\">Thanassis Rentzis, Director, \u201cThe Greek State and Audio-Visual Education\u201d<\/p>\n<p style=\"text-align: justify;\">Evangelia Themeli, Philologist, historian and film scholar \u201cCinema and school in Greece\u201d<\/p>\n<p style=\"text-align: justify;\">Evangelia Kourti, Professor of Social Psychology of Mass Media, University of Athens, \u201cFilm education within the core study matter of educators\u201d<\/p>\n<p style=\"text-align: justify;\">Sofia Papadimitriou, Director of the Educational Radio and Television Department of the Ministry of Education, Research and Religions, Greece, \u201cEducational Radio and Television 2.0: Transition to the digital age\u201d<\/p>\n<p style=\"text-align: justify;\">Renate Holubek, Media Literacy Awards, Ministry of Education, Austria, \u201cMedia literacy and democratic culture\u201d<\/p>\n<p style=\"text-align: justify;\">Antonis Papadopoulos, director &#8211; artistic director of Drama Short Film Festival, \u201cA chronicler of our time. Short films as educational tools\u201d.<\/p>\n<p style=\"text-align: justify;\">Nikos Theodosiou, Director, member of the board of Educational Group \u201cSkasiarheio\u201d (= Truant) . \u201cThe essential role of cinema in Freinet\u201d<\/p>\n<p style=\"text-align: justify;\">QUESTIONS &amp; ANSWERS &#8211; DISCUSSION<\/p>\n<p style=\"text-align: justify;\">SECOND SECTION 12:15-14:30<\/p>\n<p style=\"text-align: justify;\">Nienke Poelsma, Head of Cinekid for Professionals, The Netherlands, \u201cCineKID\u2019s educational programs\u201d<\/p>\n<p style=\"text-align: justify;\">Mikael Harbauer, Artistic director, Schlingel Festival, \u201cSchlingel Festival and its media educational activities\u201d<\/p>\n<p style=\"text-align: justify;\">Thomas Balkenhol, Instructor at \u00a0the Middle East Technical University in Ankara: \u201cThe concept of the Ankara Children\u2019s Film festival\u201d<\/p>\n<p style=\"text-align: justify;\">Nisse Koltze, Producer, Station Next, Festival director, TheNextFilmFestival, Denmark, \u201cHow and why to start local filmfestivals for schools\u201d<\/p>\n<p style=\"text-align: justify;\">Rowena Martinez Ulayan Tuzcuo\u011flu, Founding chairperson of the Children\u2019s Film and Art Association, the organization, behind the Universal Kids Film Festival, Turkey, \u201cCulture for peace through audio-visual education (The UKFF peace advocacy paradigm)\u201d<\/p>\n<p style=\"text-align: justify;\">Josep Arbiol, MICE Festival Director, Spain, \u201cMice Valencia. A funny way to media and education\u201d<\/p>\n<p style=\"text-align: justify;\">Petra Vidmar, Gustav Film Production, Slovenia: \u00a0\u201cFilm City\u201d<\/p>\n<p style=\"text-align: justify;\">Maria Leonida, Director &#8211; Karpos, Centre for Educational Activities and Intercultural Communication \u201cIn Our Own View: a versatile critical thinking project\u201d<\/p>\n<p style=\"text-align: justify;\">Voula Papayianni, \u00a0Educator\/ Innovative events and intercultural outreach Manager, Centre for Intercultural Education at National &amp; Kapodistrian University of Athens, \u201cOlympia Film Festival, a comprehensive approach in film education\u201d<\/p>\n<p style=\"text-align: justify;\">Irene Andriopoulou, Media Researcher \/ Analyst, EU Media Literacy Expert, DG Connect, EC , Member of Steering Committee on Media &amp; Information Society &#8211; CDMSI, CoE, Secretariat General for Media &amp; Communication: \u201cMaking use of film education and global outreach post film festivals\u201d<\/p>\n<p style=\"text-align: justify;\">DISCUSSION &#8211; CONCLUSIONS<\/p>\n<p style=\"text-align: justify;\">14:30 END OF MEETING<\/p>","protected":false},"excerpt":{"rendered":"<p>The Olympia International Film Festival, during its first edition in 1997, approached the issue of cinema in education and film education, by organizing an international conference in Ancient Olympia. Today, twenty years later, we are, once more, seeking the sign, by detecting the practices and concerns that have been developed over the past twenty years, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[19],"tags":[],"class_list":["post-2961","post","type-post","status-publish","format-standard","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>International Meeting Audiovisual Education: Theoretical and practical approaches - \u0394\u03b9\u03b5\u03b8\u03bd\u03ad\u03c2 \u03a6\u03b5\u03c3\u03c4\u03b9\u03b2\u03ac\u03bb \u039a\u03b9\u03bd\u03b7\u03bc\u03b1\u03c4\u03bf\u03b3\u03c1\u03ac\u03c6\u03bf\u03c5 \u039f\u03bb\u03c5\u03bc\u03c0\u03af\u03b1\u03c2 \u03b3\u03b9\u03b1 \u03a0\u03b1\u03b9\u03b4\u03b9\u03ac \u03ba\u03b1\u03b9 \u039d\u03ad\u03bf\u03c5\u03c2<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/olympiafestival.gr\/en\/news\/international-meeting-audiovisual-education-theoretical\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"International Meeting Audiovisual Education: Theoretical and practical approaches - \u0394\u03b9\u03b5\u03b8\u03bd\u03ad\u03c2 \u03a6\u03b5\u03c3\u03c4\u03b9\u03b2\u03ac\u03bb \u039a\u03b9\u03bd\u03b7\u03bc\u03b1\u03c4\u03bf\u03b3\u03c1\u03ac\u03c6\u03bf\u03c5 \u039f\u03bb\u03c5\u03bc\u03c0\u03af\u03b1\u03c2 \u03b3\u03b9\u03b1 \u03a0\u03b1\u03b9\u03b4\u03b9\u03ac \u03ba\u03b1\u03b9 \u039d\u03ad\u03bf\u03c5\u03c2\" \/>\n<meta property=\"og:description\" content=\"The Olympia International Film Festival, during its first edition in 1997, approached the issue of cinema in education and film education, by organizing an international conference in Ancient Olympia. Today, twenty years later, we are, once more, seeking the sign, by detecting the practices and concerns that have been developed over the past twenty years, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/olympiafestival.gr\/en\/news\/international-meeting-audiovisual-education-theoretical\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0394\u03b9\u03b5\u03b8\u03bd\u03ad\u03c2 \u03a6\u03b5\u03c3\u03c4\u03b9\u03b2\u03ac\u03bb \u039a\u03b9\u03bd\u03b7\u03bc\u03b1\u03c4\u03bf\u03b3\u03c1\u03ac\u03c6\u03bf\u03c5 \u039f\u03bb\u03c5\u03bc\u03c0\u03af\u03b1\u03c2 \u03b3\u03b9\u03b1 \u03a0\u03b1\u03b9\u03b4\u03b9\u03ac \u03ba\u03b1\u03b9 \u039d\u03ad\u03bf\u03c5\u03c2\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-13T11:54:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-09T13:07:50+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/olympiafestival.gr\\\/en\\\/news\\\/international-meeting-audiovisual-education-theoretical\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/olympiafestival.gr\\\/en\\\/news\\\/international-meeting-audiovisual-education-theoretical\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/olympiafestival.gr\\\/#\\\/schema\\\/person\\\/2f1ac13224689978b03c4ad1b21c03b0\"},\"headline\":\"International Meeting Audiovisual Education: Theoretical and practical approaches\",\"datePublished\":\"2018-11-13T11:54:54+00:00\",\"dateModified\":\"2021-12-09T13:07:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/olympiafestival.gr\\\/en\\\/news\\\/international-meeting-audiovisual-education-theoretical\\\/\"},\"wordCount\":600,\"publisher\":{\"@id\":\"https:\\\/\\\/olympiafestival.gr\\\/#organization\"},\"articleSection\":[\"\u039d\u03ad\u03b1\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/olympiafestival.gr\\\/en\\\/news\\\/international-meeting-audiovisual-education-theoretical\\\/\",\"url\":\"https:\\\/\\\/olympiafestival.gr\\\/en\\\/news\\\/international-meeting-audiovisual-education-theoretical\\\/\",\"name\":\"International Meeting Audiovisual Education: Theoretical and practical approaches - \u0394\u03b9\u03b5\u03b8\u03bd\u03ad\u03c2 \u03a6\u03b5\u03c3\u03c4\u03b9\u03b2\u03ac\u03bb \u039a\u03b9\u03bd\u03b7\u03bc\u03b1\u03c4\u03bf\u03b3\u03c1\u03ac\u03c6\u03bf\u03c5 \u039f\u03bb\u03c5\u03bc\u03c0\u03af\u03b1\u03c2 \u03b3\u03b9\u03b1 \u03a0\u03b1\u03b9\u03b4\u03b9\u03ac \u03ba\u03b1\u03b9 \u039d\u03ad\u03bf\u03c5\u03c2\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/olympiafestival.gr\\\/#website\"},\"datePublished\":\"2018-11-13T11:54:54+00:00\",\"dateModified\":\"2021-12-09T13:07:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/olympiafestival.gr\\\/en\\\/news\\\/international-meeting-audiovisual-education-theoretical\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/olympiafestival.gr\\\/en\\\/news\\\/international-meeting-audiovisual-education-theoretical\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/olympiafestival.gr\\\/en\\\/news\\\/international-meeting-audiovisual-education-theoretical\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae\",\"item\":\"https:\\\/\\\/olympiafestival.gr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"International Meeting Audiovisual Education: Theoretical and practical approaches\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/olympiafestival.gr\\\/#website\",\"url\":\"https:\\\/\\\/olympiafestival.gr\\\/\",\"name\":\"\u0394\u03b9\u03b5\u03b8\u03bd\u03ad\u03c2 \u03a6\u03b5\u03c3\u03c4\u03b9\u03b2\u03ac\u03bb \u039a\u03b9\u03bd\u03b7\u03bc\u03b1\u03c4\u03bf\u03b3\u03c1\u03ac\u03c6\u03bf\u03c5 \u039f\u03bb\u03c5\u03bc\u03c0\u03af\u03b1\u03c2 \u03b3\u03b9\u03b1 \u03a0\u03b1\u03b9\u03b4\u03b9\u03ac \u03ba\u03b1\u03b9 \u039d\u03ad\u03bf\u03c5\u03c2\",\"description\":\"Olympia International Film Festival for Children and Young People\",\"publisher\":{\"@id\":\"https:\\\/\\\/olympiafestival.gr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/olympiafestival.gr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/olympiafestival.gr\\\/#organization\",\"name\":\"\u0394\u03b9\u03b5\u03b8\u03bd\u03ad\u03c2 \u03a6\u03b5\u03c3\u03c4\u03b9\u03b2\u03ac\u03bb \u039a\u03b9\u03bd\u03b7\u03bc\u03b1\u03c4\u03bf\u03b3\u03c1\u03ac\u03c6\u03bf\u03c5 \u039f\u03bb\u03c5\u03bc\u03c0\u03af\u03b1\u03c2 \u03b3\u03b9\u03b1 \u03a0\u03b1\u03b9\u03b4\u03b9\u03ac \u03ba\u03b1\u03b9 \u039d\u03ad\u03bf\u03c5\u03c2\",\"url\":\"https:\\\/\\\/olympiafestival.gr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/olympiafestival.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/olympiafestival.gr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-logo512-1.png\",\"contentUrl\":\"https:\\\/\\\/olympiafestival.gr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-logo512-1.png\",\"width\":512,\"height\":389,\"caption\":\"\u0394\u03b9\u03b5\u03b8\u03bd\u03ad\u03c2 \u03a6\u03b5\u03c3\u03c4\u03b9\u03b2\u03ac\u03bb \u039a\u03b9\u03bd\u03b7\u03bc\u03b1\u03c4\u03bf\u03b3\u03c1\u03ac\u03c6\u03bf\u03c5 \u039f\u03bb\u03c5\u03bc\u03c0\u03af\u03b1\u03c2 \u03b3\u03b9\u03b1 \u03a0\u03b1\u03b9\u03b4\u03b9\u03ac \u03ba\u03b1\u03b9 \u039d\u03ad\u03bf\u03c5\u03c2\"},\"image\":{\"@id\":\"https:\\\/\\\/olympiafestival.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/olympiafestival.gr\\\/#\\\/schema\\\/person\\\/2f1ac13224689978b03c4ad1b21c03b0\",\"name\":\"admin\",\"sameAs\":[\"http:\\\/\\\/32451340138141123.blog.com.gr\"],\"url\":\"https:\\\/\\\/olympiafestival.gr\\\/en\\\/author\\\/festival_5f1o511s\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"International Meeting Audiovisual Education: Theoretical and practical approaches - \u0394\u03b9\u03b5\u03b8\u03bd\u03ad\u03c2 \u03a6\u03b5\u03c3\u03c4\u03b9\u03b2\u03ac\u03bb \u039a\u03b9\u03bd\u03b7\u03bc\u03b1\u03c4\u03bf\u03b3\u03c1\u03ac\u03c6\u03bf\u03c5 \u039f\u03bb\u03c5\u03bc\u03c0\u03af\u03b1\u03c2 \u03b3\u03b9\u03b1 \u03a0\u03b1\u03b9\u03b4\u03b9\u03ac \u03ba\u03b1\u03b9 \u039d\u03ad\u03bf\u03c5\u03c2","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/olympiafestival.gr\/en\/news\/international-meeting-audiovisual-education-theoretical\/","og_locale":"en_US","og_type":"article","og_title":"International Meeting Audiovisual Education: Theoretical and practical approaches - \u0394\u03b9\u03b5\u03b8\u03bd\u03ad\u03c2 \u03a6\u03b5\u03c3\u03c4\u03b9\u03b2\u03ac\u03bb \u039a\u03b9\u03bd\u03b7\u03bc\u03b1\u03c4\u03bf\u03b3\u03c1\u03ac\u03c6\u03bf\u03c5 \u039f\u03bb\u03c5\u03bc\u03c0\u03af\u03b1\u03c2 \u03b3\u03b9\u03b1 \u03a0\u03b1\u03b9\u03b4\u03b9\u03ac \u03ba\u03b1\u03b9 \u039d\u03ad\u03bf\u03c5\u03c2","og_description":"The Olympia International Film Festival, during its first edition in 1997, approached the issue of cinema in education and film education, by organizing an international conference in Ancient Olympia. Today, twenty years later, we are, once more, seeking the sign, by detecting the practices and concerns that have been developed over the past twenty years, [&hellip;]","og_url":"https:\/\/olympiafestival.gr\/en\/news\/international-meeting-audiovisual-education-theoretical\/","og_site_name":"\u0394\u03b9\u03b5\u03b8\u03bd\u03ad\u03c2 \u03a6\u03b5\u03c3\u03c4\u03b9\u03b2\u03ac\u03bb \u039a\u03b9\u03bd\u03b7\u03bc\u03b1\u03c4\u03bf\u03b3\u03c1\u03ac\u03c6\u03bf\u03c5 \u039f\u03bb\u03c5\u03bc\u03c0\u03af\u03b1\u03c2 \u03b3\u03b9\u03b1 \u03a0\u03b1\u03b9\u03b4\u03b9\u03ac \u03ba\u03b1\u03b9 \u039d\u03ad\u03bf\u03c5\u03c2","article_published_time":"2018-11-13T11:54:54+00:00","article_modified_time":"2021-12-09T13:07:50+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/olympiafestival.gr\/en\/news\/international-meeting-audiovisual-education-theoretical\/#article","isPartOf":{"@id":"https:\/\/olympiafestival.gr\/en\/news\/international-meeting-audiovisual-education-theoretical\/"},"author":{"name":"admin","@id":"https:\/\/olympiafestival.gr\/#\/schema\/person\/2f1ac13224689978b03c4ad1b21c03b0"},"headline":"International Meeting Audiovisual Education: Theoretical and practical approaches","datePublished":"2018-11-13T11:54:54+00:00","dateModified":"2021-12-09T13:07:50+00:00","mainEntityOfPage":{"@id":"https:\/\/olympiafestival.gr\/en\/news\/international-meeting-audiovisual-education-theoretical\/"},"wordCount":600,"publisher":{"@id":"https:\/\/olympiafestival.gr\/#organization"},"articleSection":["\u039d\u03ad\u03b1"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/olympiafestival.gr\/en\/news\/international-meeting-audiovisual-education-theoretical\/","url":"https:\/\/olympiafestival.gr\/en\/news\/international-meeting-audiovisual-education-theoretical\/","name":"International Meeting Audiovisual Education: Theoretical and practical approaches - \u0394\u03b9\u03b5\u03b8\u03bd\u03ad\u03c2 \u03a6\u03b5\u03c3\u03c4\u03b9\u03b2\u03ac\u03bb \u039a\u03b9\u03bd\u03b7\u03bc\u03b1\u03c4\u03bf\u03b3\u03c1\u03ac\u03c6\u03bf\u03c5 \u039f\u03bb\u03c5\u03bc\u03c0\u03af\u03b1\u03c2 \u03b3\u03b9\u03b1 \u03a0\u03b1\u03b9\u03b4\u03b9\u03ac \u03ba\u03b1\u03b9 \u039d\u03ad\u03bf\u03c5\u03c2","isPartOf":{"@id":"https:\/\/olympiafestival.gr\/#website"},"datePublished":"2018-11-13T11:54:54+00:00","dateModified":"2021-12-09T13:07:50+00:00","breadcrumb":{"@id":"https:\/\/olympiafestival.gr\/en\/news\/international-meeting-audiovisual-education-theoretical\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/olympiafestival.gr\/en\/news\/international-meeting-audiovisual-education-theoretical\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/olympiafestival.gr\/en\/news\/international-meeting-audiovisual-education-theoretical\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae","item":"https:\/\/olympiafestival.gr\/"},{"@type":"ListItem","position":2,"name":"International Meeting Audiovisual Education: Theoretical and practical approaches"}]},{"@type":"WebSite","@id":"https:\/\/olympiafestival.gr\/#website","url":"https:\/\/olympiafestival.gr\/","name":"Olympia Int\u2019l Film Festival for Children and Young People","description":"Olympia International Film Festival for Children and Young People","publisher":{"@id":"https:\/\/olympiafestival.gr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/olympiafestival.gr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/olympiafestival.gr\/#organization","name":"Olympia Int\u2019l Film Festival for Children and Young People","url":"https:\/\/olympiafestival.gr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/olympiafestival.gr\/#\/schema\/logo\/image\/","url":"https:\/\/olympiafestival.gr\/wp-content\/uploads\/2021\/11\/cropped-logo512-1.png","contentUrl":"https:\/\/olympiafestival.gr\/wp-content\/uploads\/2021\/11\/cropped-logo512-1.png","width":512,"height":389,"caption":"\u0394\u03b9\u03b5\u03b8\u03bd\u03ad\u03c2 \u03a6\u03b5\u03c3\u03c4\u03b9\u03b2\u03ac\u03bb \u039a\u03b9\u03bd\u03b7\u03bc\u03b1\u03c4\u03bf\u03b3\u03c1\u03ac\u03c6\u03bf\u03c5 \u039f\u03bb\u03c5\u03bc\u03c0\u03af\u03b1\u03c2 \u03b3\u03b9\u03b1 \u03a0\u03b1\u03b9\u03b4\u03b9\u03ac \u03ba\u03b1\u03b9 \u039d\u03ad\u03bf\u03c5\u03c2"},"image":{"@id":"https:\/\/olympiafestival.gr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/olympiafestival.gr\/#\/schema\/person\/2f1ac13224689978b03c4ad1b21c03b0","name":"admin","sameAs":["http:\/\/32451340138141123.blog.com.gr"],"url":"https:\/\/olympiafestival.gr\/en\/author\/festival_5f1o511s\/"}]}},"spectra_custom_meta":{"longer-permalinks-post-name-longer":["international-meeting-audiovisual-education-theoretical"],"_wpml_word_count":["{\"total\":0,\"to_translate\":{\"en\":628,\"el\":628}}"],"_top_nav_excluded":[""],"_cms_nav_minihome":[""],"_edit_last":["1"],"_wp_old_date":["2019-12-13"],"slide_template":["default"],"_wpml_media_featured":["1"],"_wpml_media_duplicate":["1"],"_last_translation_edit_mode":["translation-editor"],"_alp_processed":["1579078022"],"_edit_lock":["1639046899:1"],"classic-editor-remember":["block-editor"],"__post_views_count":["1070"],"_uag_migration_processed":["1"],"_uag_css_file_name":["uag-css-2961.css"],"_uag_js_file_name":["uag-js-2961.js"],"_uag_page_assets":["a:9:{s:3:\"css\";s:44377:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\ufeff.uagb-post-grid{margin:0 auto;position:relative}.uagb-post-grid:not(.is-grid) .uagb-post__inner-wrap{background-clip:content-box !important}.uagb-post-grid .uagb-post__inner-wrap{transition:box-shadow .2s ease;overflow:hidden}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy{display:inline-block}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy.default{margin:5px 5px 5px 0}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted{background:#444;color:#fff;border-radius:2px;flex-direction:row;align-items:flex-end;padding:6px 8px;line-height:1;margin-right:5px;margin-bottom:20px}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted a{color:#fff}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy a{text-decoration:none;color:inherit}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__image .uagb-post__image-equal-height{display:block;height:0;padding-bottom:66.67%;overflow:hidden}.uagb-post-grid .uagb-post__load-more-wrap{width:100%;position:absolute;bottom:-30px}.uagb-post-grid .uagb-post__load-more-wrap .uagb-post-pagination-button{cursor:pointer}.uagb-post-grid .uagb-post__load-more-wrap a{color:inherit}.uagb-post-grid.is-grid article{float:left;display:inline-block}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-top .uagb-post__text:nth-last-child(2){padding-bottom:100px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-top .uagb-post__text:last-child{position:absolute;bottom:20px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-background .uagb-post__text:nth-last-child(3){padding-bottom:100px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-background .uagb-post__text:nth-last-child(2){position:absolute;bottom:20px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-top .uagb-post__inner-wrap,.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-background .uagb-post__inner-wrap{position:relative}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a{display:block;height:0;overflow:hidden;position:relative}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-2-3{padding-bottom:66%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-9-16{padding-bottom:56.25%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-1-2{padding-bottom:50%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-1-1{padding-bottom:67%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-inherit{padding-bottom:0;height:auto}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-inherit img{position:unset !important}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a[class^=uagb-image-ratio-]>img{position:absolute;height:100%}.uagb-post-grid.uagb-post__items.is-masonry{display:flex;-ms-flex-wrap:wrap;-webkit-flex-wrap:wrap;flex-wrap:wrap}.uagb-post-grid.uagb-post__items.is-carousel{display:flex;-ms-flex-wrap:wrap;-webkit-flex-wrap:wrap;flex-wrap:wrap;width:100%;visibility:hidden}.uagb-post-grid.is-grid .uagb-post__inner-wrap{height:max-content}.uagb-post-grid.is-grid.uagb-post__equal-height .uagb-post__inner-wrap{height:auto}.uagb-post-grid.is-masonry .uagb-post__inner-wrap{height:auto}.uagb-post-grid .uagb-post__author span,.uagb-post-grid .uagb-post__comment span,.uagb-post-grid .uagb-post__taxonomy span,.uagb-post-grid .uagb-post__date span{font-size:inherit;line-height:inherit;width:inherit;height:inherit;margin-right:4px;vertical-align:bottom}.uagb-post-grid.uagb-post__columns-8:not(.is-grid) article{width:12.5%}.uagb-post-grid.uagb-post__columns-7:not(.is-grid) article{width:14.28%}.uagb-post-grid.uagb-post__columns-6:not(.is-grid) article{width:16.66%}.uagb-post-grid.uagb-post__columns-5:not(.is-grid) article{width:20%}.uagb-post-grid.uagb-post__columns-4:not(.is-grid) article{width:25%}.uagb-post-grid.uagb-post__columns-3:not(.is-grid) article{width:33.33%}.uagb-post-grid.uagb-post__columns-2:not(.is-grid) article{width:50%}.uagb-post-grid.uagb-post__columns-1:not(.is-grid) article{width:100%}@media only screen and (max-width: 600px){.uagb-post-grid div[class*=columns].is-grid{grid-template-columns:1fr}}.uagb-post-grid .uagb-post__image img{display:block;width:100%;height:auto;max-width:100%}.uagb-post-grid .uagb-post__title{margin-top:0;margin-bottom:0;word-break:break-word}.uagb-post-grid .uagb-post__title a{color:inherit;box-shadow:none;transition:.3s ease;text-decoration:none}.uagb-post-grid .uagb-post__title a:hover{text-decoration:none}.uagb-post-grid .uagb-post__title a:focus{text-decoration:none}.uagb-post-grid .uagb-post__title a:active{text-decoration:none}.uagb-post-grid .uagb-post-grid-byline>*{margin-right:10px}.uagb-post-grid .uagb-post-grid-byline,.uagb-post-grid .uagb-post__taxonomy{text-transform:capitalize;font-size:14px;font-weight:500;line-height:23px;text-decoration:none}.uagb-post-grid .uagb-post-grid-byline a,.uagb-post-grid .uagb-post-grid-byline a:focus,.uagb-post-grid .uagb-post-grid-byline a:active{color:inherit;font-size:inherit;text-decoration:none}.uagb-post-grid .uagb-post__title a,.uagb-post-grid .uagb-post__title a:focus,.uagb-post-grid .uagb-post__title a:active{color:inherit;font-size:inherit}.uagb-post-grid .uagb-post__author,.uagb-post-grid .uagb-post__date,.uagb-post-grid .uagb-post__comment{display:inline-block;word-break:break-all}.uagb-post-grid .uagb-post__author:not(:last-child)::after,.uagb-post-grid .uagb-post__date:not(:last-child)::after,.uagb-post-grid .uagb-post__comment:not(:last-child)::after{content:\"\u00b7\";vertical-align:middle;align-self:center;margin:0 5px;line-height:1}.uagb-post-grid .uagb-post__comment,.uagb-post-grid .uagb-post__taxonomy{display:inline-block}.uagb-post-grid .uagb-post__author a{box-shadow:none}.uagb-post-grid .uagb-post__author a:hover{color:inherit;box-shadow:0 -1px 0 inset}.uagb-post-grid .uagb-post__excerpt{word-break:break-word}.uagb-post-grid .uagb-post__inner-wrap p:last-of-type{margin-bottom:0}.uagb-post-grid .uagb-post__cta{border:none;display:inline-block;background:none}.uagb-post-grid .uagb-post__cta .ast-outline-button{display:inline-flex}.uagb-post-grid .uagb-post__excerpt p{color:inherit}.is-grid.uagb-post__items{display:grid}.wp-block-uagb-post-grid .uagb-post-pagination-wrap{grid-column:1\/-1}.uagb-post__image-position-background .uagb-post__link-complete-box{position:absolute;top:0;left:0;width:100%;height:100%;z-index:11}.uagb-post__image-position-background.uagb-post__image-enabled .uagb-post__text{color:#fff}.uagb-post__image-position-background .uagb-post__text{opacity:1;position:relative;z-index:10;overflow:hidden}.uagb-post__image-position-background .uagb-post__inner-wrap{position:relative;width:100%}.uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted,.uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__taxonomy.default{position:relative;z-index:999}.uagb-post__image-position-background .uagb-post__image img{position:absolute;width:auto;height:auto;min-width:100%;max-width:none;left:50%;top:50%;transform:translate(-50%, -50%);min-height:100%}.uagb-post__image-position-background .uagb-post__image{background-size:cover;background-repeat:no-repeat;background-position:center;overflow:hidden;text-align:center;position:absolute;left:0;top:0;width:100%;height:100%;z-index:2}.uagb-post__image-position-background .uagb-post__image::before{content:\"\";position:absolute;left:0;top:0;width:100%;height:100%;z-index:1;background-color:hsla(0,0%,100%,.5)}.uagb-slick-carousel .is-carousel{padding:0}.uagb-slick-carousel ul.slick-dots{transform:unset;position:relative;padding:unset}.uagb-slick-carousel .slick-prev:not(:hover):not(:active):not(.has-background),.uagb-slick-carousel .slick-next:not(:hover):not(:active):not(.has-background),.uagb-slick-carousel ul.slick-dots li button:not(:hover):not(:active):not(.has-background){background-color:unset}.uagb-post-grid[data-equal-height=yes] .uagb-post__inner-wrap{display:inline-block;height:100%}.uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:-45px;z-index:1}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:-45px;right:auto}.uagb-post__arrow-outside.uagb-post-grid .slick-next{right:-45px}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-next{left:auto;right:-45px}.uagb-post__arrow-inside.uagb-post-grid .slick-prev{left:25px;z-index:1}[dir=rtl] .uagb-post__arrow-inside.uagb-post-grid .slick-prev{left:auto;right:25px}.uagb-post__arrow-inside.uagb-post-grid .slick-next{right:25px}[dir=rtl] .uagb-post__arrow-inside.uagb-post-grid .slick-next{left:25px;right:auto}.uagb-post-grid.is-grid article,.uagb-post-grid.is-masonry article,.uagb-post-grid.is-carousel article{box-sizing:border-box}@media(max-width: 976px){.uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:15px;z-index:1}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:auto;right:15px}.uagb-post__arrow-outside.uagb-post-grid .slick-next{right:15px}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-next{left:15px;right:auto}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-1 article{width:100%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-2 article{width:50%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-3 article{width:33.33%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-4 article{width:25%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-5 article{width:20%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-6 article{width:16.66%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-7 article{width:14.28%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-8 article{width:12.5%}}@media(max-width: 767px){:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-1 article{width:100%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-2 article{width:50%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-3 article{width:33.33%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-4 article{width:25%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-5 article{width:20%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-6 article{width:16.66%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-7 article{width:14.28%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-8 article{width:12.5%}}.entry .entry-content .uagb-post-grid a{text-decoration:none}.uagb-post-pagination-wrap{display:flex;width:100%;flex-wrap:wrap}.uagb-post-pagination-wrap a.page-numbers,.uagb-post-pagination-wrap span.page-numbers.current{padding:5px 10px;margin:0;display:flex;margin-right:4px;margin-bottom:5px}.uagb-post-grid .uagb-post-inf-loader{margin:0 auto;min-height:58px;line-height:58px;width:160px;text-align:center}.uagb-post-grid .uagb-post-inf-loader div{width:18px;height:18px;background-color:#0085ba;-webkit-border-radius:100%;border-radius:100%;display:inline-block;-webkit-animation:sk-bouncedelay 1.4s infinite ease-in-out both;animation:sk-bouncedelay 1.4s infinite ease-in-out both}.uagb-post-grid .uagb-post-inf-loader .uagb-post-loader-1{-webkit-animation-delay:-0.32s;animation-delay:-0.32s}.uagb-post-grid .uagb-post-inf-loader .uagb-post-loader-2{-webkit-animation-delay:-0.16s;animation-delay:-0.16s}.wp-site-blocks .uagb-post__arrow-outside.uagb-post-grid .slick-next{right:0}.wp-site-blocks .uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:0}@-webkit-keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}@keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}.uagb-block-7c8162f1.is-grid .uagb-post__inner-wrap{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;box-shadow: 0px 0px 0 #00000070;}.uagb-block-7c8162f1.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: -20px;margin-right: -20px;margin-top: -20px;}.uagb-block-7c8162f1:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text:last-child{margin-bottom: 20px;}.uagb-block-7c8162f1:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text:first-child{margin-top: 20px;}.uagb-block-7c8162f1:not(.is-grid).uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__text:nth-last-child(2) {margin-bottom: 20px;}.uagb-block-7c8162f1:not(.wp-block-uagb-post-carousel):not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-7c8162f1:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-7c8162f1:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text{margin-left: 20px;margin-right: 20px;}.uagb-block-7c8162f1 .uagb-post__inner-wrap{background: #f6f6f6;text-align: left;}.uagb-block-7c8162f1 .uagb-post__inner-wrap .uagb-post__cta{padding-bottom: 0px;}.uagb-block-7c8162f1 .uagb-post__image {padding-bottom: 15px;}.uagb-block-7c8162f1 .uagb-post__title{padding-bottom: 15px;}.uagb-block-7c8162f1 .uagb-post-grid-byline{padding-bottom: 15px;}.uagb-block-7c8162f1 .uagb-post__excerpt{padding-bottom: 25px;}.uagb-block-7c8162f1 .uagb-post__image:before{background-color: #000000;opacity: 0.5;}.uagb-block-7c8162f1.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-7c8162f1.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(3 , minmax(0, 1fr));}.uagb-block-7c8162f1.is-grid .uagb-post__inner-wrap:hover{box-shadow: 0px 0px 0 #00000070;}.uagb-block-7c8162f1 .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted{color: #fff;background: #3182ce;}.uagb-block-7c8162f1 .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted a{color: #fff;}.uagb-block-7c8162f1.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: ;}.uagb-block-7c8162f1 .uagb-post-pagination-wrap{margin-top: 20px;justify-content: left;margin-left: 10px;}.uagb-block-7c8162f1 .uagb-post-pagination-wrap .page-numbers.current{background-color: #e4e4e4;color: #333333;}.uagb-block-7c8162f1 .uagb-post-pagination-wrap a{background-color: #e4e4e4;color: #777777;}.uagb-block-7c8162f1.uagb-equal_height_inline-read-more-buttons .uagb-post__inner-wrap .uagb-post__text:last-child{left: 20px;right: 20px;}.uagb-block-7c8162f1.wp-block-uagb-post-grid .uag-post-grid-wrapper{padding-right: 20px;padding-left: 20px;width: 100%;display: flex;flex-direction: column;justify-content: center;}@media only screen and (max-width: 976px) {.uagb-block-7c8162f1.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(2 , minmax(0, 1fr));}.uagb-block-7c8162f1.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-7c8162f1:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-7c8162f1:not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-7c8162f1.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-7c8162f1.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(1 , minmax(0, 1fr));}.uagb-block-7c8162f1.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-7c8162f1:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-7c8162f1:not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-7c8162f1.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}.uagb-block-7c8162f1.wp-block-uagb-post-grid .uag-post-grid-wrapper{width: unset;}}.uagb-cta__outer-wrap .uagb-cta__content,.uagb-cta__outer-wrap a.uagb-cta__block-link span,.uagb-cta__outer-wrap .uagb-cta__content-right .uagb-cta__button-wrapper,.uagb-cta__outer-wrap .uagb-cta-typeof-button,.uagb-cta__outer-wrap .uagb-cta__content-right .uagb-cta__block-link,.uagb-cta__outer-wrap .uagb-cta-with-svg{display:inline-block}.uagb-cta__outer-wrap{display:flex;justify-content:space-between}.wp-block-uagb-call-to-action .uagb-cta__buttons{display:inline-flex}.wp-block-uagb-call-to-action .wp-block-button__link,.wp-block-uagb-call-to-action .ast-outline-button{fill:currentColor;justify-content:center}.uagb-cta__button-link-wrapper,.uagb-cta-second__button{display:inline-flex;align-items:center;word-break:keep-all;width:100%}.uagb-cta__title{padding:0;margin:0;display:block}.uagb-cta__content-right .uagb-cta__button-wrapper{float:right}.uagb-cta__link-wrapper.uagb-cta__block-link-style:empty{display:none}a.uagb-cta__block-link,.entry .entry-content a.uagb-cta__block-link,a.uagb-cta__block-link-wrap,.entry .entry-content a.uagb-cta__block-link-wrap{text-decoration:none}a.uagb-cta__block-link:hover,.entry .entry-content a.uagb-cta__block-link:hover,a.uagb-cta__block-link-wrap:hover,.entry .entry-content a.uagb-cta__block-link-wrap:hover .entry .entry-content a.uagb-cta__block-link:hover{color:inherit}.uagb-cta__content-right{text-align:right;justify-content:flex-end}.uagb-cta__left-right-wrap{width:100%;word-break:break-word}.uagb-cta__icon-position-below-title .uagb-cta__left-right-wrap{display:block;min-width:100%;width:100%}.uagb-cta__icon-position-left .uagb-cta__left-right-wrap,.uagb-cta__icon-position-right .uagb-cta__left-right-wrap{display:flex}.uagb-cta__icon-position-right .uagb-cta__left-right-wrap{justify-content:flex-end}.uagb-cta__block-link-icon-after{margin-left:5px;margin-right:0}.uagb-cta__block-link-icon-before{margin-left:0;margin-right:5px}.uagb-cta__block-link-icon,.uagb-cta__block svg{transition:all 200ms linear}.uagb-cta__block{position:relative}.uagb-cta-typeof-button{line-height:1;text-align:center}.uagb-cta__content-right .uagb-cta__button-link-wrapper,.uagb-cta__content-right .uagb-cta-second__button .uagb-cta__content-right .uagb-cta__block-link,.uagb-cta__content-right.uagb-cta__button-valign-middle .uagb-cta__left-right-wrap{display:flex;align-items:center}.uagb-cta__content-right .uagb-cta__button-link-wrapper,.uagb-cta__content-right .uagb-cta-second__button .uagb-cta__content-right .uagb-cta__block-link{justify-content:center}.uagb-cta__link-wrapper a{box-shadow:none;text-decoration:none}.uagb-cta__block,.uagb-cta__content,.uagb-cta__left-right-wrap{z-index:1}.uagb-cta__block-link{cursor:pointer}.uagb-cta__content-right .uagb-cta__block-link{float:right;padding:10px 14px}a.uagb-cta__block-link-wrap{color:inherit}.uagb-cta__content p:empty{display:none}.uagb-cta__button-type-none .uagb-cta__content{width:100%}.uagb-cta-with-svg{height:14px;width:14px;line-height:14px;vertical-align:middle}.uagb-cta__block svg{display:block;height:inherit;width:inherit}.uagb-cta__button-link-wrapper svg{width:20px;height:20px}.uagb-cta__align-button-after{margin-left:5px}.uagb-cta__align-button-before{margin-right:5px}.uagb-cta__block-link i{font-style:normal}a.uagb-cta__link-to-all{position:absolute;top:0;left:0;width:100%;height:100%;z-index:11}.wp-block-uagb-call-to-action{position:relative}.wp-block-uagb-call-to-action a.uagb-cta__link-to-all{position:absolute;top:0;left:0;width:100%;height:100%;z-index:11}@media only screen and (max-width: 976px){.uagb-cta__content-stacked-tablet,.uagb-cta__content-stacked-tablet .uagb-cta__left-right-wrap{flex-direction:column;text-align:center}.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__button-wrapper{float:none;margin:0 auto}.uagb-cta__content-stacked-tablet .uagb-cta__left-right-wrap .uagb-cta__content{margin-left:0;margin-right:0}.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content,.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width:100% !important}}@media screen and (max-width: 767px){.uagb-cta__content-stacked-mobile,.uagb-cta__content-stacked-mobile .uagb-cta__left-right-wrap{flex-direction:column;text-align:center}.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__button-wrapper{float:none;margin:0 auto}.uagb-cta__content-stacked-mobile .uagb-cta__left-right-wrap .uagb-cta__content{margin-left:0;margin-right:0}.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content,.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width:100% !important}}.uagb-cta__desc p:last-child{margin-bottom:0}#uagb-cta-block-.wp-block-uagb-call-to-action .uagb-cta__title{margin-bottom: 10px;}#uagb-cta-block-.wp-block-uagb-call-to-action .uagb-cta__desc{margin-bottom: 10px;}#uagb-cta-block- .uagb-cta__align-button-after{margin-left: 10px;}#uagb-cta-block- .uagb-cta__align-button-before{margin-right: 10px;}#uagb-cta-block-.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper > svg{margin-left: 10px;}#uagb-cta-block-.wp-block-uagb-call-to-action a.uagb-cta-second__button > svg{margin-left: 10px;font-size: 14px;width: 14px;height: 14px;line-height: 14px;}#uagb-cta-block- .uagb-cta__content-wrap{text-align: left;}#uagb-cta-block- .uagb-cta__wrap{width: 70%;text-align: left;}#uagb-cta-block-.wp-block-uagb-call-to-action{text-align: left;}#uagb-cta-block- .uagb-cta__left-right-wrap .uagb-cta__content{margin-left: 0px;}#uagb-cta-block- .uagb-cta__buttons{column-gap: 15px;}#uagb-cta-block-.wp-block-uagb-call-to-action {display: flex;justify-content: space-between;}#uagb-cta-block- .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content{width: 70%;}#uagb-cta-block- .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 30%;}#uagb-cta-block-.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper {align-self: center;height: fit-content;margin-left: auto;}#uagb-cta-block-.wp-block-uagb-call-to-action  {flex-direction: row;align-items: center;}#uagb-cta-block-.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button{align-self: center;height: fit-content;}#uagb-cta-block-.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button:hover{background-color: !important;}#uagb-cta-block-.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button:focus{background-color: !important;}#uagb-cta-block- .uagb-cta__button-wrapper a.uagb-cta-typeof-button{color: #333;border-style: solid;}#uagb-cta-block-.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__buttons a.uagb-cta__button-link-wrapper.wp-block-button__link{border-style: solid;}#uagb-cta-block-.wp-block-uagb-call-to-action a.uagb-cta-second__button{text-transform: normal;text-decoration: none;font-size: 14px;}@media only screen and (max-width: 976px) {#uagb-cta-block-.wp-block-uagb-call-to-action.uagb-cta__content-stacked-tablet {display: inherit;}#uagb-cta-block-.uagb-cta__content-stacked-tablet .uagb-cta__wrap{width: 100%;}#uagb-cta-block- .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 30%;}#uagb-cta-block- .uagb-cta__wrap{text-align: center;}#uagb-cta-block-.wp-block-uagb-call-to-action {flex-direction: column;align-items: center;}}@media only screen and (max-width: 767px) {#uagb-cta-block-.wp-block-uagb-call-to-action.uagb-cta__content-stacked-mobile {display: inherit;}#uagb-cta-block-.uagb-cta__content-stacked-mobile .uagb-cta__wrap{width: 100%;}#uagb-cta-block- .uagb-cta__buttons{justify-content: center;}#uagb-cta-block- .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 30%;}#uagb-cta-block- .uagb-cta__wrap{text-align: center;}#uagb-cta-block-.wp-block-uagb-call-to-action {flex-direction: column;align-items: center;}}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.uagb-block-d987bd3d.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-d987bd3d.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-d987bd3d.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-d987bd3d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-d987bd3d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-d987bd3d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-d987bd3d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-d987bd3d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-d987bd3d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-d987bd3d.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-d987bd3d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-d987bd3d.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-d987bd3d.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-d987bd3d.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-d987bd3d.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-d987bd3d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-d987bd3d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uagb-block-0ade5b77.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-0ade5b77.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-0ade5b77.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-0ade5b77.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-0ade5b77.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-0ade5b77.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-0ade5b77.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-0ade5b77.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-0ade5b77.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-0ade5b77.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-0ade5b77.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-0ade5b77.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-0ade5b77.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-0ade5b77.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-0ade5b77.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-0ade5b77.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-0ade5b77.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uagb-block-6378eebf.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-6378eebf.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-6378eebf.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-6378eebf.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-6378eebf.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-6378eebf.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-6378eebf.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-6378eebf.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-6378eebf.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-6378eebf.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-6378eebf.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-6378eebf.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-6378eebf.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-6378eebf.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-6378eebf.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-6378eebf.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-6378eebf.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uagb-block-b81bf894.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-b81bf894.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-b81bf894.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-b81bf894.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-b81bf894.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-b81bf894.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-b81bf894.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-b81bf894.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-b81bf894.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-b81bf894.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-b81bf894.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-b81bf894.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-b81bf894.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-b81bf894.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-b81bf894.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-b81bf894.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-b81bf894.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uagb-buttons__outer-wrap .uagb-buttons__wrap{display:inline-flex;width:100%}.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}@media(max-width: 976px){.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}@media(max-width: 767px){.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}.uagb-buttons__outer-wrap .uagb-buttons-repeater{display:flex;justify-content:center;align-items:center;transition:box-shadow .2s ease}.uagb-buttons__outer-wrap .uagb-buttons-repeater a.uagb-button__link{display:flex;justify-content:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon{font-size:inherit;display:flex;align-items:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon svg{fill:currentColor;width:inherit;height:inherit}.uagb-block-0e983f40.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-0e983f40.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.wp-block-uagb-buttons .uagb-block-97d557c5 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-97d557c5 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-97d557c5 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-97d557c5 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-97d557c5 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-97d557c5.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-97d557c5.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-97d557c5 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;}.wp-block-uagb-buttons .uagb-block-97d557c5 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-97d557c5 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-97d557c5 .uagb-button__link{text-transform: normal;text-decoration: none;}@media only screen and (max-width: 976px) {.uagb-block-0e983f40.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-0e983f40.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-97d557c5.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-97d557c5 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}}@media only screen and (max-width: 767px) {.uagb-block-0e983f40.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-0e983f40.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-97d557c5.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-97d557c5 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}}\";s:2:\"js\";s:161:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-97d557c5' );\n});\n });\";s:18:\"current_block_list\";a:22:{i:0;s:10:\"core\/group\";i:2;s:12:\"core\/heading\";i:3;s:13:\"core\/archives\";i:4;s:15:\"core\/categories\";i:5;s:14:\"uagb\/post-grid\";i:6;s:17:\"core\/latest-posts\";i:7;s:10:\"core\/image\";i:8;s:21:\"mailchimp-for-wp\/form\";i:9;s:14:\"core\/shortcode\";i:10;s:17:\"core\/social-links\";i:11;s:16:\"core\/social-link\";i:12;s:26:\"ultimate-post\/social-icons\";i:13;s:20:\"ultimate-post\/social\";i:14;s:19:\"uagb\/call-to-action\";i:15;s:10:\"uagb\/image\";i:16;s:12:\"uagb\/buttons\";i:17;s:18:\"uagb\/buttons-child\";i:18;s:22:\"stackable\/button-group\";i:19;s:16:\"stackable\/button\";i:20;s:15:\"stackable\/image\";i:21;s:21:\"ultimate-post\/heading\";i:22;s:14:\"core\/paragraph\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1787886825\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"ultp_layout_landscape_large":false,"ultp_layout_landscape":false,"ultp_layout_portrait":false,"ultp_layout_square":false},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/olympiafestival.gr\/en\/author\/festival_5f1o511s\/"},"uagb_comment_info":0,"uagb_excerpt":"The Olympia International Film Festival, during its first edition in 1997, approached the issue of cinema in education and film education, by organizing an international conference in Ancient Olympia. Today, twenty years later, we are, once more, seeking the sign, by detecting the practices and concerns that have been developed over the past twenty years,&hellip;","_links":{"self":[{"href":"https:\/\/olympiafestival.gr\/en\/wp-json\/wp\/v2\/posts\/2961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/olympiafestival.gr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/olympiafestival.gr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/olympiafestival.gr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/olympiafestival.gr\/en\/wp-json\/wp\/v2\/comments?post=2961"}],"version-history":[{"count":0,"href":"https:\/\/olympiafestival.gr\/en\/wp-json\/wp\/v2\/posts\/2961\/revisions"}],"wp:attachment":[{"href":"https:\/\/olympiafestival.gr\/en\/wp-json\/wp\/v2\/media?parent=2961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/olympiafestival.gr\/en\/wp-json\/wp\/v2\/categories?post=2961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/olympiafestival.gr\/en\/wp-json\/wp\/v2\/tags?post=2961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}